{"id":37819,"date":"2021-02-01T06:30:45","date_gmt":"2021-02-01T05:30:45","guid":{"rendered":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth"},"modified":"2021-02-01T06:30:45","modified_gmt":"2021-02-01T05:30:45","slug":"minitits-e23-iced-earth","status":"publish","type":"podcast","link":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth","title":{"rendered":"MiniTITS-E23: Iced Earth"},"content":{"rendered":"<p>MINITITS E23 Iced Earth<\/p>\n<p>Guillaume, un ami qui ne nous veut pas que du bien s\u2019est pay\u00e9 un Minitits en bonne et due forme et nous a enjoint (de weed, de carrelage ?) \u00e0 parler de Iced Earth et plus pr\u00e9cis\u00e9ment d\u2019Horror Show. Alors Iced Earth : Maiden marque rep\u00e8re ou vrai groupe valable ? John Shaffer, visionnaire \u00e9clair\u00e9 ou sac \u00e0 purin ? Voici quelques unes des questions que l\u2019on ne se pose pas sp\u00e9cialement dans ce podcast o\u00f9 s\u2019entrem\u00eale Jason Siegel, Howard Stern et du r\u00e9pulsif \u00e0 ours. Ce monde n\u2019a plus aucun sens.<\/p>\n<p>Comme d\u2019habitude retrouvez nous sur nos r\u00e9seaux socials, notamment Facebook pour la gaudriole et Twitter o\u00f9 l\u2019on poste une fois par an. Suivez Sam braver le couvre feu en for\u00e7ant les rideaux de fer des bars du 5\u00e8me arrondissement et \u00e9ventuellement Mathieu sur instagram (@Iro22 pour de jolies photos de vinyles).<\/p>\n<p>Si vous voulez nous filer quelques ronds (m\u00eame en dessous de 40 euros y a des trucs) c\u2019est ici que \u00e7a se passe : https:\/\/fr.tipeee.com\/trollinthesky<\/p>\n<p>Si vous voulez acheter du r\u00e9pulsif \u00e0 ours, ce serait compl\u00e8tement stupide mais c\u2019est possible ici : https:\/\/www.sabrered.com\/r%C3%A9pulsif-canadien-en-a%C3%A9rosol-pour-ours<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MINITITS E23 Iced Earth Guillaume, un ami qui ne nous veut pas que du bien s\u2019est pay\u00e9 un Minitits en bonne et due forme et nous a enjoint (de weed, de carrelage ?) \u00e0 parler de Iced Earth et plus pr\u00e9cis\u00e9ment d\u2019Horror Show. Alors Iced Earth : Maiden marque<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"https:\/\/desert-rock.com\/tits\/MiniTITS23-IcedEarth.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-47.jpg","cover_image_id":"37820","duration":"51:24","filesize":"81.47M","filesize_raw":"85423253","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3209],"class_list":["post-37819","podcast","type-podcast","status-publish","hentry","series-troll-in-the-sky"],"episode_featured_image":false,"episode_player_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-47.jpg","download_link":"https:\/\/desert-rock.com\/site\/podcast-download\/37819\/minitits-e23-iced-earth","player_link":"https:\/\/desert-rock.com\/site\/podcast-player\/37819\/minitits-e23-iced-earth","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/desert-rock.com\/site\/podcast-player\/37819\/minitits-e23-iced-earth\">https:\/\/desert-rock.com\/site\/podcast-player\/37819\/minitits-e23-iced-earth<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/fr\/podcast\/troll-in-the-sky\/id1299543811","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/desert-rock.com\/site\/feed\/podcast\/troll-in-the-sky","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"pAx9Hdln19\"><a href=\"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth\">MiniTITS-E23: Iced Earth<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth\/embed#?secret=pAx9Hdln19\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0MiniTITS-E23: Iced Earth\u00a0\u00bb &#8212; Desert-rock.com\" data-secret=\"pAx9Hdln19\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/desert-rock.com\/site\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MiniTITS-E23: Iced Earth - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MiniTITS-E23: Iced Earth - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"MINITITS E23 Iced Earth Guillaume, un ami qui ne nous veut pas que du bien s\u2019est pay\u00e9 un Minitits en bonne et due forme et nous a enjoint (de weed, de carrelage ?) \u00e0 parler de Iced Earth et plus pr\u00e9cis\u00e9ment d\u2019Horror Show. Alors Iced Earth : Maiden marque\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/minitits-e23-iced-earth\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/minitits-e23-iced-earth\",\"name\":\"MiniTITS-E23: Iced Earth - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"datePublished\":\"2021-02-01T05:30:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/minitits-e23-iced-earth#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/minitits-e23-iced-earth\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/minitits-e23-iced-earth#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MiniTITS-E23: Iced Earth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MiniTITS-E23: Iced Earth - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth","og_locale":"fr_FR","og_type":"article","og_title":"MiniTITS-E23: Iced Earth - Desert-rock.com","og_description":"MINITITS E23 Iced Earth Guillaume, un ami qui ne nous veut pas que du bien s\u2019est pay\u00e9 un Minitits en bonne et due forme et nous a enjoint (de weed, de carrelage ?) \u00e0 parler de Iced Earth et plus pr\u00e9cis\u00e9ment d\u2019Horror Show. Alors Iced Earth : Maiden marque","og_url":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth","url":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth","name":"MiniTITS-E23: Iced Earth - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"datePublished":"2021-02-01T05:30:45+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/podcast\/minitits-e23-iced-earth#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Episode","item":"https:\/\/desert-rock.com\/site\/podcast"},{"@type":"ListItem","position":3,"name":"MiniTITS-E23: Iced Earth"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast\/37819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=37819"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=37819"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=37819"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/series?post=37819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}