{"id":37853,"date":"2020-03-23T08:00:16","date_gmt":"2020-03-23T07:00:16","guid":{"rendered":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais"},"modified":"2020-03-23T08:00:16","modified_gmt":"2020-03-23T07:00:16","slug":"tits-e39-le-black-metal-francais","status":"publish","type":"podcast","link":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais","title":{"rendered":"TITS E39: Le Black Metal Fran\u00e7ais"},"content":{"rendered":"<p>TITS E39 : Le Black Metal Fran\u00e7ais. Baptiste s\u2019est pay\u00e9 son TITS en payant, depuis un an, son obole sur Tipee via le Wall Of J\u00e9richo Macias. Et ce brave sudiste a voulu nous parler de deux des sp\u00e9cialit\u00e9s de son patelin: l\u2019ennui et le rejet de l\u2019autre. Id\u00e9al pour tailler le bout de gras autour du black metal fran\u00e7ais, lui raconter \u00e0 quel point on trouve \u00e7a merdique, faire semblant de s\u2019int\u00e9resser aux groupes dont il parle et lui faire comprendre, avec la p\u00e9dagogie qui est la notre, \u00e0 quel point la vie est une f\u00eate, que rien n\u2019est plus beau que de se m\u00ealer aux autres, que rien ne vaut le brassage des cultures. Bon c\u2019\u00e9tait 48 heures avant un confinement mondial total du au Covid19 \u00e0 cause de ces putains de chinois qui font rien qu\u2019\u00e0 nous refiler leurs merdes \u00e0 force de bouffer du pangolin. Fermez moi ces fronti\u00e8res, filez nous une guitare et du mascara qu\u2019on se mette au NSBM !<\/p>\n<p>Toujours la page Tipee pour nous proposer des sujets passionnant que l\u2019on traitera avec le professionnalisme qui est le notre : https:\/\/fr.tipeee.com\/trollinthesky(d\u2019ailleurs Baptiste a lib\u00e9r\u00e9 sa place dans le Wall Of Jericho Macias, alors profitez en, seule place dispo pour l\u2019ann\u00e9e).<\/p>\n<p>N\u2019oubliez pas que mercredi 25 mars \u00e0 21h30 nous faisons une COVID\u00e9o TITS live sur Youtube intitul\u00e9e : \u00ab Cellule psychologique pour metalleux fragiles \u00bb. Connectez vous on pourra dire des b\u00eatises ensemble !<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TITS E39 : Le Black Metal Fran\u00e7ais. Baptiste s\u2019est pay\u00e9 son TITS en payant, depuis un an, son obole sur Tipee via le Wall Of J\u00e9richo Macias. Et ce brave sudiste a voulu nous parler de deux des sp\u00e9cialit\u00e9s de son patelin: l\u2019ennui et le rejet de l\u2019autre. I<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"https:\/\/desert-rock.com\/tits\/TITS39-BlackMetalFrancais.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-64.jpg","cover_image_id":"37854","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3209],"class_list":["post-37853","podcast","type-podcast","status-publish","hentry","series-troll-in-the-sky"],"episode_featured_image":false,"episode_player_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-64.jpg","download_link":"https:\/\/desert-rock.com\/site\/podcast-download\/37853\/tits-e39-le-black-metal-francais","player_link":"https:\/\/desert-rock.com\/site\/podcast-player\/37853\/tits-e39-le-black-metal-francais","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/desert-rock.com\/site\/podcast-player\/37853\/tits-e39-le-black-metal-francais\">https:\/\/desert-rock.com\/site\/podcast-player\/37853\/tits-e39-le-black-metal-francais<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/fr\/podcast\/troll-in-the-sky\/id1299543811","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/desert-rock.com\/site\/feed\/podcast\/troll-in-the-sky","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"apVyN8pQoU\"><a href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais\">TITS E39: Le Black Metal Fran\u00e7ais<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais\/embed#?secret=apVyN8pQoU\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0TITS E39: Le Black Metal Fran\u00e7ais\u00a0\u00bb &#8212; Desert-rock.com\" data-secret=\"apVyN8pQoU\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/desert-rock.com\/site\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"TITS E39 : Le Black Metal Fran\u00e7ais. Baptiste s\u2019est pay\u00e9 son TITS en payant, depuis un an, son obole sur Tipee via le Wall Of J\u00e9richo Macias. Et ce brave sudiste a voulu nous parler de deux des sp\u00e9cialit\u00e9s de son patelin: l\u2019ennui et le rejet de l\u2019autre. I\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e39-le-black-metal-francais\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e39-le-black-metal-francais\",\"name\":\"TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"datePublished\":\"2020-03-23T07:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e39-le-black-metal-francais#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e39-le-black-metal-francais\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e39-le-black-metal-francais#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TITS E39: Le Black Metal Fran\u00e7ais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais","og_locale":"fr_FR","og_type":"article","og_title":"TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com","og_description":"TITS E39 : Le Black Metal Fran\u00e7ais. Baptiste s\u2019est pay\u00e9 son TITS en payant, depuis un an, son obole sur Tipee via le Wall Of J\u00e9richo Macias. Et ce brave sudiste a voulu nous parler de deux des sp\u00e9cialit\u00e9s de son patelin: l\u2019ennui et le rejet de l\u2019autre. I","og_url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais","url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais","name":"TITS E39: Le Black Metal Fran\u00e7ais - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"datePublished":"2020-03-23T07:00:16+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e39-le-black-metal-francais#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Episode","item":"https:\/\/desert-rock.com\/site\/podcast"},{"@type":"ListItem","position":3,"name":"TITS E39: Le Black Metal Fran\u00e7ais"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast\/37853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=37853"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=37853"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=37853"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/series?post=37853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}