{"id":37909,"date":"2019-01-21T08:00:16","date_gmt":"2019-01-21T07:00:16","guid":{"rendered":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames"},"modified":"2019-01-21T08:00:16","modified_gmt":"2019-01-21T07:00:16","slug":"tits-e25-growl-de-dames","status":"publish","type":"podcast","link":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames","title":{"rendered":"TITS-E25: Growl de Dames"},"content":{"rendered":"<p>TITSE25 : Growl de Dames. Avec l\u2019aimable participation de Roxanne, inconsciente r\u00e9fugi\u00e9e Iranniene plus Pits que Bacardi, vos deux irr\u00e9ductibles trolls brossent l\u2019histoire des femmes dans le metal, avec autant de pr\u00e9cision et de respect qu\u2019\u00e0 l\u2019accoutum\u00e9e. Suivez nous comme d\u2019habitude sur vos applications de podcast, sur youtube et dans Valeurs Actuelles, et n\u2019h\u00e9sitez pas \u00e0 nous filer un pourboire sur https:\/\/fr.tipeee.com\/trollinthesky. Dieu ne vous le rendra pas mais on continuera \u00e0 vous faire marrer. Pas autant que Valeurs Actuelles mais on fera de notre mieux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TITSE25 : Growl de Dames. Avec l\u2019aimable participation de Roxanne, inconsciente r\u00e9fugi\u00e9e Iranniene plus Pits que Bacardi, vos deux irr\u00e9ductibles trolls brossent l\u2019histoire des femmes dans le metal, avec autant de pr\u00e9cision et de respect qu\u2019\u00e0 l\u2019accoutum\u00e9e<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"https:\/\/desert-rock.com\/tits\/TITS25-Growldedames.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-92.jpg","cover_image_id":"37910","duration":"1:22:14","filesize":"150.72M","filesize_raw":"158042767","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3209],"class_list":["post-37909","podcast","type-podcast","status-publish","hentry","series-troll-in-the-sky"],"episode_featured_image":false,"episode_player_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-92.jpg","download_link":"https:\/\/desert-rock.com\/site\/podcast-download\/37909\/tits-e25-growl-de-dames","player_link":"https:\/\/desert-rock.com\/site\/podcast-player\/37909\/tits-e25-growl-de-dames","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/desert-rock.com\/site\/podcast-player\/37909\/tits-e25-growl-de-dames\">https:\/\/desert-rock.com\/site\/podcast-player\/37909\/tits-e25-growl-de-dames<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/fr\/podcast\/troll-in-the-sky\/id1299543811","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/desert-rock.com\/site\/feed\/podcast\/troll-in-the-sky","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"ELk2EdcZAA\"><a href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames\">TITS-E25: Growl de Dames<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames\/embed#?secret=ELk2EdcZAA\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0TITS-E25: Growl de Dames\u00a0\u00bb &#8212; Desert-rock.com\" data-secret=\"ELk2EdcZAA\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/desert-rock.com\/site\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TITS-E25: Growl de Dames - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TITS-E25: Growl de Dames - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"TITSE25 : Growl de Dames. Avec l\u2019aimable participation de Roxanne, inconsciente r\u00e9fugi\u00e9e Iranniene plus Pits que Bacardi, vos deux irr\u00e9ductibles trolls brossent l\u2019histoire des femmes dans le metal, avec autant de pr\u00e9cision et de respect qu\u2019\u00e0 l\u2019accoutum\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e25-growl-de-dames\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e25-growl-de-dames\",\"name\":\"TITS-E25: Growl de Dames - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"datePublished\":\"2019-01-21T07:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e25-growl-de-dames#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e25-growl-de-dames\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e25-growl-de-dames#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TITS-E25: Growl de Dames\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TITS-E25: Growl de Dames - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames","og_locale":"fr_FR","og_type":"article","og_title":"TITS-E25: Growl de Dames - Desert-rock.com","og_description":"TITSE25 : Growl de Dames. Avec l\u2019aimable participation de Roxanne, inconsciente r\u00e9fugi\u00e9e Iranniene plus Pits que Bacardi, vos deux irr\u00e9ductibles trolls brossent l\u2019histoire des femmes dans le metal, avec autant de pr\u00e9cision et de respect qu\u2019\u00e0 l\u2019accoutum\u00e9e","og_url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames","url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames","name":"TITS-E25: Growl de Dames - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"datePublished":"2019-01-21T07:00:16+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e25-growl-de-dames#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Episode","item":"https:\/\/desert-rock.com\/site\/podcast"},{"@type":"ListItem","position":3,"name":"TITS-E25: Growl de Dames"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast\/37909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=37909"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=37909"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=37909"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/series?post=37909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}