{"id":37947,"date":"2018-01-22T08:00:57","date_gmt":"2018-01-22T07:00:57","guid":{"rendered":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv"},"modified":"2018-01-22T08:00:57","modified_gmt":"2018-01-22T07:00:57","slug":"tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","status":"publish","type":"podcast","link":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","title":{"rendered":"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv."},"content":{"rendered":"<p>TITS E09 : \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. Bande sonore : Judas Priest \u2013 Painkiller \/ Body Count \u2013 Talk Shit, Get Shot \/ Oranssi Pazuzu \u2013 Sienipilvi \/ Dal\u00ebk \u2013 Bricks Crumble \/ Sons Of Otis \u2013 Mile High \/ Evoken \u2013 Tragedy Eternal \/ Hooded Menace \u2013 Effigies Of Evil \/ Bell Witch &#8211; Judgement, In Fire: I \u2013 Garden (Of Blooming Ash) \/ Jex Thoth \u2013 The Places You Walk \/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TITS E09 : \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. Bande sonore : Judas Priest \u2013 Painkiller \/ Body Count \u2013 Talk Shit, Get Shot \/ Oranssi Pazuzu \u2013 Sienipilvi \/ Dal\u00ebk \u2013 Bricks Crumble \/ Sons Of Otis \u2013 M<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"https:\/\/desert-rock.com\/tits\/TITS09-Umlautdemerde.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-111.jpg","cover_image_id":"37948","duration":"1:06:27","filesize":"91.41M","filesize_raw":"95850525","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3209],"class_list":["post-37947","podcast","type-podcast","status-publish","hentry","series-troll-in-the-sky"],"episode_featured_image":false,"episode_player_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-111.jpg","download_link":"https:\/\/desert-rock.com\/site\/podcast-download\/37947\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","player_link":"https:\/\/desert-rock.com\/site\/podcast-player\/37947\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/desert-rock.com\/site\/podcast-player\/37947\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\">https:\/\/desert-rock.com\/site\/podcast-player\/37947\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/fr\/podcast\/troll-in-the-sky\/id1299543811","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/desert-rock.com\/site\/feed\/podcast\/troll-in-the-sky","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2VyKpggKbp\"><a href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\">TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv.<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\/embed#?secret=2VyKpggKbp\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv.\u00a0\u00bb &#8212; Desert-rock.com\" data-secret=\"2VyKpggKbp\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/desert-rock.com\/site\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"TITS E09 : \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. Bande sonore : Judas Priest \u2013 Painkiller \/ Body Count \u2013 Talk Shit, Get Shot \/ Oranssi Pazuzu \u2013 Sienipilvi \/ Dal\u00ebk \u2013 Bricks Crumble \/ Sons Of Otis \u2013 M\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\",\"name\":\"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"datePublished\":\"2018-01-22T07:00:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","og_locale":"fr_FR","og_type":"article","og_title":"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com","og_description":"TITS E09 : \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. Bande sonore : Judas Priest \u2013 Painkiller \/ Body Count \u2013 Talk Shit, Get Shot \/ Oranssi Pazuzu \u2013 Sienipilvi \/ Dal\u00ebk \u2013 Bricks Crumble \/ Sons Of Otis \u2013 M","og_url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv","name":"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv. - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"datePublished":"2018-01-22T07:00:57+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e09-umlaut-de-merde-une-plongee-dans-la-programmation-des-fetivaux-feat-max-de-2-guys-1-tv#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Episode","item":"https:\/\/desert-rock.com\/site\/podcast"},{"@type":"ListItem","position":3,"name":"TITS-E09: \u00ab Umlaut de merde \u00bb : une plong\u00e9e dans la programmation des fetivaux feat Max de 2 guys 1 Tv."}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast\/37947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=37947"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=37947"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=37947"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/series?post=37947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}