{"id":37955,"date":"2017-11-27T08:00:07","date_gmt":"2017-11-27T07:00:07","guid":{"rendered":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses"},"modified":"2017-11-27T08:00:07","modified_gmt":"2017-11-27T07:00:07","slug":"tits-e05-metal-up-tes-fesses","status":"publish","type":"podcast","link":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses","title":{"rendered":"TITS-E05: Metal up tes fesses"},"content":{"rendered":"<p>TITS E05: Metal up tes fesses. De jeunes thrasheux de g\u00e9nie \u00e0 r\u00e9actionnaires au riff s\u00e9nile, ils ont tout \u00e9t\u00e9, du meilleur au pire, et surtout sont aujourd&#8217;hui encore le plus gros groupe de metal de tous les temps. Une discographie en 3 p\u00e9riodes, un roux, un mort et Bob Rock, qui a eu sur leur musique un r\u00f4le comparable \u00e0 celui de Zahia pour l&#8217;\u00e9quipe de France. Proc\u00e8s, esclavagisme et chocolat, bienvenu dans le monde de Metallica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TITS E05: Metal up tes fesses. De jeunes thrasheux de g\u00e9nie \u00e0 r\u00e9actionnaires au riff s\u00e9nile, ils ont tout \u00e9t\u00e9, du meilleur au pire, et surtout sont aujourd&#8217;hui encore le plus gros groupe de metal de tous les temps. Une discographie en 3 p\u00e9riodes, u<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"","ping_status":"closed","template":"","meta":{"episode_type":"","audio_file":"https:\/\/desert-rock.com\/tits\/TITS05-Metal-up-tes-fesses.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-115.jpg","cover_image_id":"37956","duration":"1:27:11","filesize":"119.88M","filesize_raw":"125702899","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3209],"class_list":["post-37955","podcast","type-podcast","status-publish","hentry","series-troll-in-the-sky"],"episode_featured_image":false,"episode_player_image":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/02\/tits-1-115.jpg","download_link":"https:\/\/desert-rock.com\/site\/podcast-download\/37955\/tits-e05-metal-up-tes-fesses","player_link":"https:\/\/desert-rock.com\/site\/podcast-player\/37955\/tits-e05-metal-up-tes-fesses","audio_player":"<a class=\"wp-embedded-audio\" href=\"https:\/\/desert-rock.com\/site\/podcast-player\/37955\/tits-e05-metal-up-tes-fesses\">https:\/\/desert-rock.com\/site\/podcast-player\/37955\/tits-e05-metal-up-tes-fesses<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/fr\/podcast\/troll-in-the-sky\/id1299543811","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/desert-rock.com\/site\/feed\/podcast\/troll-in-the-sky","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2QsivVu5Bp\"><a href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses\">TITS-E05: Metal up tes fesses<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses\/embed#?secret=2QsivVu5Bp\" width=\"500\" height=\"350\" title=\"\u00ab\u00a0TITS-E05: Metal up tes fesses\u00a0\u00bb &#8212; Desert-rock.com\" data-secret=\"2QsivVu5Bp\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/desert-rock.com\/site\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TITS-E05: Metal up tes fesses - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TITS-E05: Metal up tes fesses - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"TITS E05: Metal up tes fesses. De jeunes thrasheux de g\u00e9nie \u00e0 r\u00e9actionnaires au riff s\u00e9nile, ils ont tout \u00e9t\u00e9, du meilleur au pire, et surtout sont aujourd&#8217;hui encore le plus gros groupe de metal de tous les temps. Une discographie en 3 p\u00e9riodes, u\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e05-metal-up-tes-fesses\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e05-metal-up-tes-fesses\",\"name\":\"TITS-E05: Metal up tes fesses - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"datePublished\":\"2017-11-27T07:00:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e05-metal-up-tes-fesses#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e05-metal-up-tes-fesses\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\\\/tits-e05-metal-up-tes-fesses#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Episode\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/podcast\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TITS-E05: Metal up tes fesses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TITS-E05: Metal up tes fesses - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses","og_locale":"fr_FR","og_type":"article","og_title":"TITS-E05: Metal up tes fesses - Desert-rock.com","og_description":"TITS E05: Metal up tes fesses. De jeunes thrasheux de g\u00e9nie \u00e0 r\u00e9actionnaires au riff s\u00e9nile, ils ont tout \u00e9t\u00e9, du meilleur au pire, et surtout sont aujourd&#8217;hui encore le plus gros groupe de metal de tous les temps. Une discographie en 3 p\u00e9riodes, u","og_url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses","url":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses","name":"TITS-E05: Metal up tes fesses - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"datePublished":"2017-11-27T07:00:07+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/podcast\/tits-e05-metal-up-tes-fesses#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Episode","item":"https:\/\/desert-rock.com\/site\/podcast"},{"@type":"ListItem","position":3,"name":"TITS-E05: Metal up tes fesses"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast\/37955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=37955"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=37955"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=37955"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/series?post=37955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}