{"id":1277,"date":"2015-02-18T16:37:16","date_gmt":"2015-02-18T15:37:16","guid":{"rendered":"http:\/\/desert-rock.com\/dr\/autoprods\/?p=1277"},"modified":"2026-03-15T14:03:15","modified_gmt":"2026-03-15T13:03:15","slug":"space-fisters-vol-1","status":"publish","type":"post","link":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html","title":{"rendered":"Space Fisters &#8211; Vol.1"},"content":{"rendered":"<p style=\"text-align: center\"><a href=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/02\/Space-Fisters-Vol.1-cover.jpg\"><img decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-1278\" alt=\"Space Fisters - Vol.1 - cover\" src=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/02\/Space-Fisters-Vol.1-cover-205x205.jpg\" width=\"170\" height=\"170\" \/><\/a><\/p>\n<p>Si la montagne ne vous gagne pas en ces temps hivernaux, laissez-vous tenter par ces trois furieux savoyards que sont les Space Fisters. Cranves-Sales est officiellement devenu si\u00e8ge des futurs lancements des fus\u00e9es exploratrices du fuzzo-espace. Le trio ne se contente pas de parcourir la galaxie \u00e0 coups de virtuosit\u00e9 instrumentale. Non, comme leur nom l\u2019indique, l\u2019espace ils le retournent, le parcourent, l\u2019approfondissent, vers l\u2019infini et l\u2019au-del\u00e0\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<p>Ce Vol. 1 c\u2019est une pouss\u00e9e de d\u00e9collage qui vous scotche \u00e0 vos enceintes. L\u2019apesanteur n\u2019aura plus prise sur vous face \u00e0 cette nouvelle forme de gravit\u00e9 qui op\u00e9rera sur vos tympans qu\u00e9mandeur d\u2019encore plus de d\u00e9luges de riffs. Car chez Space Fisters on con\u00e7oit les pluies de m\u00e9t\u00e9orites de mani\u00e8re vari\u00e9e, riches en m\u00e9lodies et en parpaings. C\u2019est de la lourdeur au service du psych\u00e9d\u00e9lisme, du jam de doom, du sludge survitamin\u00e9, du blues sous amphet, c\u2019est les 60\u2019s dans un trou noir de fuzz, c\u2019est un alliage de titane et de formica. Le groupe fait fi des structures et des conventions et les passages chant\u00e9s ne peuvent freiner les vell\u00e9it\u00e9s de laisser les cordes et les peaux parler. Quatre titres pour 36 minutes orgasmiques. Du groove \u00e0 en faire trembler les tr\u00e9fonds de l\u2019univers par une section rythmique qui sonne organique, naturelle dans ses nuances comme dans ses changements de tempo, ses multiples cassures et autres contre-temps. On sent les savoyards s\u00fbrs de leurs montures et ils ne les m\u00e9nagent pas.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019unit\u00e9 et la coh\u00e9rence qui ressort de ces morceaux est \u00e0 en faire p\u00e2lir les jammeurs les plus forcen\u00e9s. Space Fisters n\u2019existe que depuis juin 2012 mais cet album concr\u00e9tise r\u00e9ellement deux ann\u00e9es de travail, de ma\u00eetrise et d\u2019un savoir-faire pour que l\u2019auditeur au-del\u00e0 de la jubilation atteigne une v\u00e9ritable extase. Qu\u2019il est vain de chercher \u00e0 rationnaliser les signaux que font recevoir vos esgourdes, cet album lanc\u00e9 c\u2019est le troisi\u00e8me type qui vient vous cueillir aux abords de la voie lact\u00e9e. La production est pr\u00e9cise dans son gras. Les aigus \u00e7a emp\u00eache de d\u00e9coller ou de coller tout court. Over-saturation, \u00e9chos sur la voix, spatialisation de l\u2019ensemble avec suffisamment d\u2019air pour ne pas perdre conscience face aux apparitions hallucinatoires. C\u2019est lourd, gras, puissant mais enlev\u00e9 \u00e0 la fois, c\u2019est le cosmos qui s\u2019\u00e9veille d\u2019un big-bang.<\/p>\n<p>&nbsp;<\/p>\n<p>Maintenant que le Vol. 1 est sorti fin 2014, vivement leur Holy Mountain et leur Dopesmoker\u2026 Space Fisters se chauffe de ce bois l\u00e0 (mais pas que) et les de plus en plus r\u00e9currentes occasions de les voir en live ne le d\u00e9mentent pas. Un futur grand nom de la sc\u00e8ne fran\u00e7aise (mais pas que&#8230;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si la montagne ne vous gagne pas en ces temps hivernaux, laissez-vous tenter par ces trois furieux savoyards que sont les Space Fisters. Cranves-Sales est officiellement devenu si\u00e8ge des futurs lancements des fus\u00e9es exploratrices du fuzzo-espace. Le trio ne se contente pas de parcourir la galaxie \u00e0 coups de virtuosit\u00e9 instrumentale. Non, comme leur nom [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[624,1853,1665,1667],"tags":[4,3230,467],"class_list":["post-1277","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-624","category-aint-one","category-autoprods","category-disques","tag-4","tag-autoproduction","tag-space-fisters"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Space Fisters - Vol.1 - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Space Fisters - Vol.1 - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"Si la montagne ne vous gagne pas en ces temps hivernaux, laissez-vous tenter par ces trois furieux savoyards que sont les Space Fisters. Cranves-Sales est officiellement devenu si\u00e8ge des futurs lancements des fus\u00e9es exploratrices du fuzzo-espace. Le trio ne se contente pas de parcourir la galaxie \u00e0 coups de virtuosit\u00e9 instrumentale. Non, comme leur nom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-18T15:37:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-15T13:03:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"376\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ain&#039;t One\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ain&#039;t One\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html\"},\"author\":{\"name\":\"Ain't One\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/dc7f3a4dac048e67fabe8c9c2170f863\"},\"headline\":\"Space Fisters &#8211; Vol.1\",\"datePublished\":\"2015-02-18T15:37:16+00:00\",\"dateModified\":\"2026-03-15T13:03:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/j2-monstermagnet2.jpg\",\"keywords\":[\"2014\",\"Autoproduction\",\"Space Fisters\"],\"articleSection\":[\"2014\",\"Ain't-One\",\"Autoproduction\",\"Disques\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html\",\"name\":\"Space Fisters - Vol.1 - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/j2-monstermagnet2.jpg\",\"datePublished\":\"2015-02-18T15:37:16+00:00\",\"dateModified\":\"2026-03-15T13:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#primaryimage\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/j2-monstermagnet2.jpg\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/07\\\/j2-monstermagnet2.jpg\",\"width\":550,\"height\":376},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/space-fisters-vol-1.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Space Fisters &#8211; Vol.1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/dc7f3a4dac048e67fabe8c9c2170f863\",\"name\":\"Ain't One\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g\",\"caption\":\"Ain't One\"},\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/author\\\/aintone\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Space Fisters - Vol.1 - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html","og_locale":"fr_FR","og_type":"article","og_title":"Space Fisters - Vol.1 - Desert-rock.com","og_description":"Si la montagne ne vous gagne pas en ces temps hivernaux, laissez-vous tenter par ces trois furieux savoyards que sont les Space Fisters. Cranves-Sales est officiellement devenu si\u00e8ge des futurs lancements des fus\u00e9es exploratrices du fuzzo-espace. Le trio ne se contente pas de parcourir la galaxie \u00e0 coups de virtuosit\u00e9 instrumentale. Non, comme leur nom [&hellip;]","og_url":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","article_published_time":"2015-02-18T15:37:16+00:00","article_modified_time":"2026-03-15T13:03:15+00:00","og_image":[{"width":550,"height":376,"url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg","type":"image\/jpeg"}],"author":"Ain't One","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ain't One","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#article","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html"},"author":{"name":"Ain't One","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/dc7f3a4dac048e67fabe8c9c2170f863"},"headline":"Space Fisters &#8211; Vol.1","datePublished":"2015-02-18T15:37:16+00:00","dateModified":"2026-03-15T13:03:15+00:00","mainEntityOfPage":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"image":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg","keywords":["2014","Autoproduction","Space Fisters"],"articleSection":["2014","Ain't-One","Autoproduction","Disques"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html","url":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html","name":"Space Fisters - Vol.1 - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#primaryimage"},"image":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg","datePublished":"2015-02-18T15:37:16+00:00","dateModified":"2026-03-15T13:03:15+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#primaryimage","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/07\/j2-monstermagnet2.jpg","width":550,"height":376},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/space-fisters-vol-1.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Space Fisters &#8211; Vol.1"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]},{"@type":"Person","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/dc7f3a4dac048e67fabe8c9c2170f863","name":"Ain't One","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/690f2793f9334748f93be817984fcb8d53649ca0aa53ea41d0dcc87f19a43af9?s=96&d=mm&r=g","caption":"Ain't One"},"url":"https:\/\/desert-rock.com\/site\/author\/aintone"}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/1277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=1277"}],"version-history":[{"count":1,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/1277\/revisions"}],"predecessor-version":[{"id":39069,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/1277\/revisions\/39069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media\/1278"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=1277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/categories?post=1277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=1277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}