{"id":16807,"date":"2012-01-01T15:31:13","date_gmt":"2012-01-01T15:31:13","guid":{"rendered":"http:\/\/www.desert-rock.com\/dr\/chrocd\/ironweed-indian-ladder.html"},"modified":"2012-01-01T15:31:13","modified_gmt":"2012-01-01T15:31:13","slug":"ironweed-indian-ladder","status":"publish","type":"post","link":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html","title":{"rendered":"Ironweed &#8211; Indian Ladder"},"content":{"rendered":"<div align=\"center\"><img decoding=\"async\" alt=\"Ironweed - Indian Ladder\" src=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/ironweed.jpg\" alt=\"\" width=\"205\" height=\"205\" border=\"0\" hspace=\"5\" vspace=\"5\" \/><\/div>\n<p style=\"text-align: left;\">Ben \u00e7a alors : Greatdayforup n&rsquo;est plus&#8230; et il faut que je l&rsquo;apprenne en lisant la bio de ces inf\u00e2mes Ironweed. Car oui, Ironweed est n\u00e9 des cendres encore chaudes des excellents Greatdayforup. Snif. Paix \u00e0 leur \u00e2me. Voyons ce que leurs rejetons ont dans le ventre.<\/p>\n<p style=\"text-align: left;\">Du coup, le genre pratiqu\u00e9 par nos 5 lascars ne surprend pas totalement : faisant parfois penser \u00e0 un Alabama TunderPussy sans racines sudistes, le metal stonerien des new yorkais se vautre occasionnellement dans des relents sludge bien craspecs. Pensez Mastodon-meets-Bongzilla, Down-meets-High On Fire pour avoir une id\u00e9e, mais avec des vocaux moins gravos. Un d\u00e9lice. Ironweed balance la sauce d\u00e8s les premi\u00e8res minutes et ne rel\u00e2che pas la pression. Les titres d\u00e9filent, les riffs aussi, soit gras et visqueux, enrob\u00e9s d&rsquo;une basse ronflante (\u00ab\u00a0Rid the earth\u00a0\u00bb, ou encore \u00ab\u00a0Lifeless coil\u00a0\u00bb, doomy et glaireux \u00e0 souhait), soit secs et incisifs, rentre-dedans et totalement metal dans l&rsquo;esprit (\u00ab\u00a0Vertigo\u00a0\u00bb, \u00ab\u00a0The faithless will\u00a0\u00bb). Un ravissement des cages \u00e0 miel, \u00e0 d\u00e9conseiller aux chochottes et aux fans de Julien Dor\u00e9.<\/p>\n<p style=\"text-align: left;\">L&rsquo;incorporation de Jeff Andrews aux vocaux est une b\u00e9n\u00e9diction : l&rsquo;un des points faibles de Greatdayforup se retrouve ainsi \u00ab\u00a0corrig\u00e9\u00a0\u00bb par l&rsquo;apport de ce vocaliste ne manquant ni de puissance dans ses beuglements, ni de nuances dans ses choeurs, un recrutement tout \u00e0 fait appropri\u00e9.<\/p>\n<p style=\"text-align: left;\">\u00ab\u00a0Indian Ladder\u00a0\u00bb se r\u00e9v\u00e8le \u00eatre une excellente galette de la part de ce nouveau groupe, qui prend la rel\u00e8ve au moins aussi haut que les impressionnants Greatdayforup l&rsquo;avaient laiss\u00e9e. Une bien jolie pi\u00e8ce, un album qui en impose et qui pour ma part s&rsquo;est creus\u00e9 une place de choix dans ma playlist pendant plusieurs semaines&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ben \u00e7a alors : Greatdayforup n&rsquo;est plus&#8230; et il faut que je l&rsquo;apprenne en lisant la bio de ces inf\u00e2mes Ironweed. Car oui, Ironweed est n\u00e9 des cendres encore chaudes des excellents Greatdayforup. Snif. Paix \u00e0 leur \u00e2me. Voyons ce que leurs rejetons ont dans le ventre. Du coup, le genre pratiqu\u00e9 par nos 5 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[618,1667,1670],"tags":[649,2087,454],"class_list":["post-16807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-618","category-disques","category-laurent","tag-649","tag-ironweed","tag-small-stone-records"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ironweed - Indian Ladder - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ironweed - Indian Ladder - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"Ben \u00e7a alors : Greatdayforup n&rsquo;est plus&#8230; et il faut que je l&rsquo;apprenne en lisant la bio de ces inf\u00e2mes Ironweed. Car oui, Ironweed est n\u00e9 des cendres encore chaudes des excellents Greatdayforup. Snif. Paix \u00e0 leur \u00e2me. Voyons ce que leurs rejetons ont dans le ventre. Du coup, le genre pratiqu\u00e9 par nos 5 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-01T15:31:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/ironweed.jpg\" \/>\n<meta name=\"author\" content=\"Laurent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html\"},\"author\":{\"name\":\"Laurent\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/aa78023c9b441176ec5b66e541591373\"},\"headline\":\"Ironweed &#8211; Indian Ladder\",\"datePublished\":\"2012-01-01T15:31:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ironweed.jpg\",\"keywords\":[\"2008\",\"Ironweed\",\"small stone records\"],\"articleSection\":[\"2008\",\"Disques\",\"Laurent\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html\",\"name\":\"Ironweed - Indian Ladder - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ironweed.jpg\",\"datePublished\":\"2012-01-01T15:31:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#primaryimage\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ironweed.jpg\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/ironweed.jpg\",\"width\":170,\"height\":170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/ironweed-indian-ladder.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ironweed &#8211; Indian Ladder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/aa78023c9b441176ec5b66e541591373\",\"name\":\"Laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"caption\":\"Laurent\"},\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/author\\\/laurent\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ironweed - Indian Ladder - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html","og_locale":"fr_FR","og_type":"article","og_title":"Ironweed - Indian Ladder - Desert-rock.com","og_description":"Ben \u00e7a alors : Greatdayforup n&rsquo;est plus&#8230; et il faut que je l&rsquo;apprenne en lisant la bio de ces inf\u00e2mes Ironweed. Car oui, Ironweed est n\u00e9 des cendres encore chaudes des excellents Greatdayforup. Snif. Paix \u00e0 leur \u00e2me. Voyons ce que leurs rejetons ont dans le ventre. Du coup, le genre pratiqu\u00e9 par nos 5 [&hellip;]","og_url":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","article_published_time":"2012-01-01T15:31:13+00:00","og_image":[{"url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/ironweed.jpg","type":"","width":"","height":""}],"author":"Laurent","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Laurent","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#article","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html"},"author":{"name":"Laurent","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/aa78023c9b441176ec5b66e541591373"},"headline":"Ironweed &#8211; Indian Ladder","datePublished":"2012-01-01T15:31:13+00:00","mainEntityOfPage":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"image":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/03\/ironweed.jpg","keywords":["2008","Ironweed","small stone records"],"articleSection":["2008","Disques","Laurent"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html","url":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html","name":"Ironweed - Indian Ladder - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#primaryimage"},"image":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/03\/ironweed.jpg","datePublished":"2012-01-01T15:31:13+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#primaryimage","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/03\/ironweed.jpg","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2026\/03\/ironweed.jpg","width":170,"height":170},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/ironweed-indian-ladder.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Ironweed &#8211; Indian Ladder"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]},{"@type":"Person","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/aa78023c9b441176ec5b66e541591373","name":"Laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","caption":"Laurent"},"url":"https:\/\/desert-rock.com\/site\/author\/laurent"}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/16807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=16807"}],"version-history":[{"count":0,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/16807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media\/39528"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=16807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/categories?post=16807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=16807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}