{"id":22142,"date":"2014-04-28T09:22:17","date_gmt":"2014-04-28T09:22:17","guid":{"rendered":"http:\/\/desert-rock.com\/dr\/chrocd\/?p=22142"},"modified":"2014-04-28T09:22:17","modified_gmt":"2014-04-28T09:22:17","slug":"brave-black-sea-fragments","status":"publish","type":"post","link":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html","title":{"rendered":"Brave Black Sea &#8211; Fragments"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-22143\" alt=\"braveblacksea-fragments\" src=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-205x205.jpg\" width=\"170\" height=\"170\" srcset=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-205x205.jpg 205w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-140x140.jpg 140w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-100x100.jpg 100w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-45x45.jpg 45w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments-150x150.jpg 150w\" sizes=\"(max-width: 170px) 100vw, 170px\" \/><\/p>\n<p style=\"text-align: left;\">Il nous arrive de chroniquer des albums assez \u00e9loign\u00e9s de notre genre de pr\u00e9dilection, le stoner. Pourquoi me direz vous? Et bien un nom d&rsquo;artiste, un label, une vague relation et on s\u2019int\u00e9resse, on est comme \u00e7a nous, curieux de tout&#8230; C&rsquo;est exactement ce qui m&rsquo;a attir\u00e9 dans ce projet et voil\u00e0 pourquoi vous \u00eates en train de lire cette (courte) chronique sur ce site.<br \/>\nMais concr\u00e8tement, pourquoi celui-ci plut\u00f4t qu&rsquo;un autre. Excusez du peu mais on trouve quand m\u00eame dans ce groupe deux anciens membres de <strong>Slo Burn<\/strong> (<strong>Damon Garrison<\/strong> et <strong>Chris Hale<\/strong>) qui est \u00e0 mon sens la d\u00e9finition m\u00eame du stoner et derri\u00e8re les f\u00fbts un certain <strong>Alfredo Hernandez<\/strong>. Si ces trois noms ne vous suffisent pas \u00e0 vous faire saliver, en tous cas moi oui et \u00e9norm\u00e9ment!<br \/>\nSauf que si comme moi vous avez en t\u00eate les noms de <strong>Slo Burn<\/strong> et d&rsquo;<strong>Alfredo Hernandez<\/strong> au moment de mettre la galette dans la platine, vous risquez de d\u00e9chanter s\u00e9v\u00e8re. Pas que l&rsquo;album soit mauvais \u00e7a non, mais juste que c&rsquo;est bien \u00e9loign\u00e9 de ce que j&rsquo;avais esp\u00e9r\u00e9. Voil\u00e0 un bon disque de rock, mais un bon disque comme il est existe des dizaines. On flirte avec un c\u00f4t\u00e9 grunge plus ou moins assum\u00e9 mais attention, un grunge d\u00e9poussi\u00e9r\u00e9, bien clean, on est bien loin d&rsquo;un <strong>Mudhoney<\/strong> par exemple. On tourne plut\u00f4t du c\u00f4t\u00e9 de <strong>Bush<\/strong>, en moins p\u00eachu encore avec un chanteur qui a du beaucoup \u00e9couter <strong>Layne Staley<\/strong> avant d&rsquo;enregistrer, mais il est loin d&rsquo;en avoir le talent. Les compos sont honn\u00eates sans plus, l&rsquo;album est tr\u00e8s bien produit mais voil\u00e0 quoi, \u00e7a s&rsquo;oublie aussi vite que \u00e7a s&rsquo;\u00e9coute. Un groupe qui aura du mal \u00e0 percer, surtout que la promo se fait autour d&rsquo;un incontournable \u00ab\u00a0avec des membres de <strong>Kyuss<\/strong>, <strong>Queens of the Stone Age<\/strong> et <strong>Slo Burn<\/strong>\u00ab\u00a0&#8230;<br \/>\nBon sur ce je vous laisse, je vais aller m&rsquo;\u00e9couter un bon vieux <em>Suck You Dry<\/em> et un petit <em>Positiva<\/em> dans la foul\u00e9e tiens&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nous arrive de chroniquer des albums assez \u00e9loign\u00e9s de notre genre de pr\u00e9dilection, le stoner. Pourquoi me direz vous? Et bien un nom d&rsquo;artiste, un label, une vague relation et on s\u2019int\u00e9resse, on est comme \u00e7a nous, curieux de tout&#8230; C&rsquo;est exactement ce qui m&rsquo;a attir\u00e9 dans ce projet et voil\u00e0 pourquoi vous \u00eates [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[624,1667,1651],"tags":[4,2783,2784],"class_list":["post-22142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-624","category-disques","category-shinkibo","tag-4","tag-brave-black-sea","tag-v2-records"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brave Black Sea - Fragments - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brave Black Sea - Fragments - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"Il nous arrive de chroniquer des albums assez \u00e9loign\u00e9s de notre genre de pr\u00e9dilection, le stoner. Pourquoi me direz vous? Et bien un nom d&rsquo;artiste, un label, une vague relation et on s\u2019int\u00e9resse, on est comme \u00e7a nous, curieux de tout&#8230; C&rsquo;est exactement ce qui m&rsquo;a attir\u00e9 dans ce projet et voil\u00e0 pourquoi vous \u00eates [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-28T09:22:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"395\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"shinkibo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"shinkibo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html\"},\"author\":{\"name\":\"shinkibo\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/5502b95cd4bcf8831a7bc47eb4868354\"},\"headline\":\"Brave Black Sea &#8211; Fragments\",\"datePublished\":\"2014-04-28T09:22:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/braveblacksea-fragments.jpg\",\"keywords\":[\"2014\",\"Brave Black Sea\",\"V2 Records\"],\"articleSection\":[\"2014\",\"Disques\",\"Shinkibo\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html\",\"name\":\"Brave Black Sea - Fragments - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/braveblacksea-fragments.jpg\",\"datePublished\":\"2014-04-28T09:22:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#primaryimage\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/braveblacksea-fragments.jpg\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/braveblacksea-fragments.jpg\",\"width\":395,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/brave-black-sea-fragments.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brave Black Sea &#8211; Fragments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/5502b95cd4bcf8831a7bc47eb4868354\",\"name\":\"shinkibo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g\",\"caption\":\"shinkibo\"},\"sameAs\":[\"https:\\\/\\\/desert-rock.com\\\/site\"],\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/author\\\/shinkibo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brave Black Sea - Fragments - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html","og_locale":"fr_FR","og_type":"article","og_title":"Brave Black Sea - Fragments - Desert-rock.com","og_description":"Il nous arrive de chroniquer des albums assez \u00e9loign\u00e9s de notre genre de pr\u00e9dilection, le stoner. Pourquoi me direz vous? Et bien un nom d&rsquo;artiste, un label, une vague relation et on s\u2019int\u00e9resse, on est comme \u00e7a nous, curieux de tout&#8230; C&rsquo;est exactement ce qui m&rsquo;a attir\u00e9 dans ce projet et voil\u00e0 pourquoi vous \u00eates [&hellip;]","og_url":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","article_published_time":"2014-04-28T09:22:17+00:00","og_image":[{"width":395,"height":400,"url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg","type":"image\/jpeg"}],"author":"shinkibo","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"shinkibo","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#article","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html"},"author":{"name":"shinkibo","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/5502b95cd4bcf8831a7bc47eb4868354"},"headline":"Brave Black Sea &#8211; Fragments","datePublished":"2014-04-28T09:22:17+00:00","mainEntityOfPage":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"image":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg","keywords":["2014","Brave Black Sea","V2 Records"],"articleSection":["2014","Disques","Shinkibo"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html","url":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html","name":"Brave Black Sea - Fragments - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#primaryimage"},"image":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg","datePublished":"2014-04-28T09:22:17+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#primaryimage","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2014\/04\/braveblacksea-fragments.jpg","width":395,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/brave-black-sea-fragments.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Brave Black Sea &#8211; Fragments"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]},{"@type":"Person","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/5502b95cd4bcf8831a7bc47eb4868354","name":"shinkibo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19004bbf19e78960202e4206e1f3f5372661cd2435575c8f11b32e119ec82e5f?s=96&d=mm&r=g","caption":"shinkibo"},"sameAs":["https:\/\/desert-rock.com\/site"],"url":"https:\/\/desert-rock.com\/site\/author\/shinkibo"}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/22142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=22142"}],"version-history":[{"count":0,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/22142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media\/22143"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=22142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/categories?post=22142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=22142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}