{"id":22905,"date":"2015-09-10T14:10:10","date_gmt":"2015-09-10T12:10:10","guid":{"rendered":"http:\/\/desert-rock.com\/dr\/chrocd\/?p=22905"},"modified":"2015-09-10T14:10:10","modified_gmt":"2015-09-10T12:10:10","slug":"windhand-griefs-infernal-flowers","status":"publish","type":"post","link":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html","title":{"rendered":"Windhand &#8211; Grief&rsquo;s Infernal Flower"},"content":{"rendered":"<p align=\"JUSTIFY\"><a href=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg\"><img decoding=\"async\" class=\"size-thumbnail wp-image-22906 aligncenter\" alt=\"griefsinfernalflower_1500\" src=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-205x205.jpg\" width=\"170\" height=\"170\" srcset=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-205x205.jpg 205w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-140x140.jpg 140w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-100x100.jpg 100w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-45x45.jpg 45w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-300x300.jpg 300w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-768x768.jpg 768w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-1024x1024.jpg 1024w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500-150x150.jpg 150w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg 1500w\" sizes=\"(max-width: 170px) 100vw, 170px\" \/><\/a><\/p>\n<p align=\"JUSTIFY\">Il est donc l\u00e0, face \u00e0 moi, le mur colossal que je dois franchir pour entrevoir la lumi\u00e8re. Quelques rais pourtant parviennent \u00e0 se faufiler entre les jointures crasses et, chauffant mes joues poilues de poupon p\u00e9p\u00e8re, me promettent un apr\u00e8s somptueux. Faut dire qu&rsquo;il va avoir du boulot le soleil s&rsquo;il veut percer le doom de Windhand. En 2013, le quintet am\u00e9ricain avait assombri le ciel avec un \u00ab\u00a0Soma\u00a0\u00bb lourd, tirant sa noirceur des oracles sabbathiens et electric wizardiens, creusant sa tombe dans la l\u00e9gion zombie d\u2019ersatz de qualit\u00e9. L&rsquo;\u00e9vidente question concernant le nouvel opus \u00ab\u00a0Grief&rsquo;s infernal Flower \u00bb, est de savoir si les musiciens de Richmond ont r\u00e9ussi \u00e0 insuffler plus de personnalit\u00e9 et d&rsquo;identit\u00e9 \u00e0 leur doom de qualit\u00e9.<\/p>\n<p align=\"JUSTIFY\">Toujours chez Relapse et produit par Jack Endino (Nirvana, Soundgarden, High On Fire), \u00ab\u00a0Grief&rsquo;s infernal Flower \u00bb commence l\u00e0 o\u00f9 avait finit son pr\u00e9d\u00e9cesseur. Rien de bien nouveau sous les nuages, un stoner-doom de qualit\u00e9 ralentissant le rythme cardiaque mais respirant toujours les m\u00eames productions opiac\u00e9es inh\u00e9rentes au genre. Le fait d&rsquo;avoir une chanteuse ne change d&rsquo;ailleurs pas la donne dans ces moments l\u00e0 car la voix est travaill\u00e9e de telle mani\u00e8re qu&rsquo;elle pourrait sortir d&rsquo;une trach\u00e9e trans genre et impersonnelle. On se retrouve donc \u00e0 \u00e9couter des titres tels \u00ab\u00a0Two Urns\u00a0\u00bb ou \u00ab\u00a0Tanngrisnir\u00a0\u00bb en dodelinant sa m\u00e9lancolie mais sans r\u00e9elle surprise.<\/p>\n<p align=\"JUSTIFY\">D&rsquo;o\u00f9 vient que ce nouvel album pourrait surprendre\u00a0? A vrai dire, c&rsquo;est une fois de plus dans le sillon du folk noir que Windhand est int\u00e9ressant. Sur Soma, c&rsquo;est le titre \u00ab\u00a0Evergreen\u00a0\u00bb qui convoquait les sorci\u00e8res de Salem autour d&rsquo;un feu de camp froid comme la mort. Ballade d\u00e9pouill\u00e9e et r\u00eache, elle faisait des merveilles. Aujourd&rsquo;hui, c&rsquo;est \u00ab\u00a0Aition\u00bb et \u00ab\u00a0Sparrow Us\u00a0\u00bb qui s&rsquo;y collent. Car oui, enfin, la voix de Dorthia Cottrell trouve dans une guitare s\u00e8che, l&rsquo;\u00e9crin mortuaire parfait pour narrer sa tristesse. Et l&rsquo;on regrette que l&rsquo;album ne comporte pas plus d&rsquo;\u00e9l\u00e9ments acoustiques. Il suffit d&rsquo;\u00e9couter l&rsquo;intro de \u00ab\u00a0Crypt Key\u00a0\u00bb pour s&rsquo;en convaincre. Ces instants folks subliment le doom des am\u00e9ricains, offrent un contrepoint parfait aux murs de saturation et dirigent la chanteuse vers des chemins plus personnels. La frustration est d&rsquo;autant plus grande que le talent et le son sont l\u00e0 mais que ces touches acoustiques ne sont pas l\u00e9gions.<\/p>\n<p align=\"JUSTIFY\">On \u00e9coute donc un bel exercice de style mais pas un album charni\u00e8re dans la carri\u00e8re de Windhand. Il faudra plus qu&rsquo;une ou deux chansons folk par disque pour s&rsquo;extirper de la masse. Pourtant les ingr\u00e9dients sont l\u00e0, les saveurs pr\u00e9sentes, reste \u00e0 les cuisiner diff\u00e9remment peut-\u00eatre. Le dosage pour r\u00e9aliser un bon poison (coucou \u00e0 la famille Borgia en passant) est affaire d&rsquo;\u00e9quilibre et nul doute que le folk sombre d\u00e9velopp\u00e9 entre ses riffs permettra aux am\u00e9ricains d&rsquo;y parvenir. Curieux donc de go\u00fbter au prochain chaudron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est donc l\u00e0, face \u00e0 moi, le mur colossal que je dois franchir pour entrevoir la lumi\u00e8re. Quelques rais pourtant parviennent \u00e0 se faufiler entre les jointures crasses et, chauffant mes joues poilues de poupon p\u00e9p\u00e8re, me promettent un apr\u00e8s somptueux. Faut dire qu&rsquo;il va avoir du boulot le soleil s&rsquo;il veut percer le [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":22906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[625,1667,2121],"tags":[5,1766,577],"class_list":["post-22905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-625","category-disques","category-flaux","tag-5","tag-relapse-records","tag-windhand"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Windhand - Grief&#039;s Infernal Flower - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windhand - Grief&#039;s Infernal Flower - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"Il est donc l\u00e0, face \u00e0 moi, le mur colossal que je dois franchir pour entrevoir la lumi\u00e8re. Quelques rais pourtant parviennent \u00e0 se faufiler entre les jointures crasses et, chauffant mes joues poilues de poupon p\u00e9p\u00e8re, me promettent un apr\u00e8s somptueux. Faut dire qu&rsquo;il va avoir du boulot le soleil s&rsquo;il veut percer le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-10T12:10:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flaux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html\"},\"author\":{\"name\":\"Flaux\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/294190bf55a2a74cff4255325c4f82ca\"},\"headline\":\"Windhand &#8211; Grief&rsquo;s Infernal Flower\",\"datePublished\":\"2015-09-10T12:10:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html\"},\"wordCount\":526,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/griefsinfernalflower_1500.jpg\",\"keywords\":[\"2015\",\"Relapse Records\",\"windhand\"],\"articleSection\":[\"2015\",\"Disques\",\"Flaux\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html\",\"name\":\"Windhand - Grief's Infernal Flower - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/griefsinfernalflower_1500.jpg\",\"datePublished\":\"2015-09-10T12:10:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#primaryimage\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/griefsinfernalflower_1500.jpg\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2015\\\/09\\\/griefsinfernalflower_1500.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/windhand-griefs-infernal-flowers.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Windhand &#8211; Grief&rsquo;s Infernal Flower\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/294190bf55a2a74cff4255325c4f82ca\",\"name\":\"Flaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g\",\"caption\":\"Flaux\"},\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/author\\\/flaux\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Windhand - Grief's Infernal Flower - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html","og_locale":"fr_FR","og_type":"article","og_title":"Windhand - Grief's Infernal Flower - Desert-rock.com","og_description":"Il est donc l\u00e0, face \u00e0 moi, le mur colossal que je dois franchir pour entrevoir la lumi\u00e8re. Quelques rais pourtant parviennent \u00e0 se faufiler entre les jointures crasses et, chauffant mes joues poilues de poupon p\u00e9p\u00e8re, me promettent un apr\u00e8s somptueux. Faut dire qu&rsquo;il va avoir du boulot le soleil s&rsquo;il veut percer le [&hellip;]","og_url":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","article_published_time":"2015-09-10T12:10:10+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg","type":"image\/jpeg"}],"author":"Flaux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Flaux","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#article","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html"},"author":{"name":"Flaux","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/294190bf55a2a74cff4255325c4f82ca"},"headline":"Windhand &#8211; Grief&rsquo;s Infernal Flower","datePublished":"2015-09-10T12:10:10+00:00","mainEntityOfPage":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html"},"wordCount":526,"commentCount":0,"publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"image":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg","keywords":["2015","Relapse Records","windhand"],"articleSection":["2015","Disques","Flaux"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html","url":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html","name":"Windhand - Grief's Infernal Flower - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#primaryimage"},"image":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg","datePublished":"2015-09-10T12:10:10+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#primaryimage","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2015\/09\/griefsinfernalflower_1500.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/windhand-griefs-infernal-flowers.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Windhand &#8211; Grief&rsquo;s Infernal Flower"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]},{"@type":"Person","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/294190bf55a2a74cff4255325c4f82ca","name":"Flaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/62cc659dda6c83f13c849504ced18dcd5e0cd386429644f54e0499afbf87f5c5?s=96&d=mm&r=g","caption":"Flaux"},"url":"https:\/\/desert-rock.com\/site\/author\/flaux"}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/22905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=22905"}],"version-history":[{"count":0,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/22905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media\/22906"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=22905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/categories?post=22905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=22905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}