{"id":30906,"date":"2023-04-11T07:28:18","date_gmt":"2023-04-11T05:28:18","guid":{"rendered":"https:\/\/desert-rock.com\/dr\/chrocd\/?p=30906"},"modified":"2026-02-25T18:15:49","modified_gmt":"2026-02-25T17:15:49","slug":"sandrider-enveletration","status":"publish","type":"post","link":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html","title":{"rendered":"Sandrider &#8211; Enveletration"},"content":{"rendered":"<p><a href=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg\"><img decoding=\"async\" class=\"size-thumbnail wp-image-30907 aligncenter\" src=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-205x205.jpg\" alt=\"\" width=\"205\" height=\"205\" srcset=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-205x205.jpg 205w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-48x48.jpg 48w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-300x300.jpg 300w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-250x250.jpg 250w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-550x550.jpg 550w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-800x800.jpg 800w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-180x180.jpg 180w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-500x500.jpg 500w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-140x140.jpg 140w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-100x100.jpg 100w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-45x45.jpg 45w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-768x768.jpg 768w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-1024x1024.jpg 1024w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration-150x150.jpg 150w, https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg 1500w\" sizes=\"(max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<p>Quatre ! Cet \u00e9nigmatiquement d\u00e9nomm\u00e9 <em>Enveletration<\/em> est rien moins que le quatri\u00e8me disque de ce groupe \u00e9tasunien pass\u00e9 largement sous les radars, apr\u00e8s pourtant plus d&rsquo;une douzaine d&rsquo;ann\u00e9es d&rsquo;existence. Encha\u00eenant les labels obscurs, rien, hormis un coup de chance, n&rsquo;aurait pu laisser pr\u00e9juger que cette situation change un jour, tant la notori\u00e9t\u00e9 et la force de frappe promotionnelle de leur nouvelle maison d&rsquo;accueil, Satanik Royalty Records, ne sont pas vraiment reconnues. Et pourtant, quel disque ! Qu&rsquo;il aurait \u00e9t\u00e9 dommage de passer \u00e0 c\u00f4t\u00e9&#8230;<\/p>\n<p>Sandrider c&rsquo;est un peu l&rsquo;enfant cach\u00e9 de ASG et de Torche, o\u00f9 se m\u00e8le un peu la puissance et l&rsquo;\u00e9nergie d\u00e9brid\u00e9es du Mastodon d\u00e9but de carri\u00e8re (quand il se d\u00e9tachait un peu de ses penchants thrash et ne versait pas encore dans les travers proggy&#8230;). De la m\u00e9lodie, du refrain qui imprime, du riff qui attaque, et encore un peu de m\u00e9lodie pour la route. La rythmique tabasse et groove, tandis que Jon Weisnewski tapisse la texture m\u00e9lodique de beaux pans de guitare, riches, omnipr\u00e9sents.<\/p>\n<p>On sourit un peu au d\u00e9but, gentiment, au fil des premi\u00e8res \u00e9coutes, en particulier de ces refrains, qui souvent semblent se cantonner \u00e0 gueuler de mani\u00e8re r\u00e9p\u00e9titive le titre (mono-mot, toujours) de la chanson. Mais les tours de disque s&rsquo;encha\u00eenant, on entre la t\u00eate la premi\u00e8re et on se laisse absorber insidieusement dans cette succession quasi enivrante de chansons : les hits s&rsquo;encha\u00eenent \u00e0 haute vitesse et haute densit\u00e9 (10 compos en 36 minutes, c&rsquo;est un d\u00e9ferlement de torgnoles, et que du maigre).<\/p>\n<p>Se d\u00e9marquent quelques titres n\u00e9anmoins, tel ce furieux \u00ab\u00a0Tourniquet\u00a0\u00bb, le tr\u00e8s accrocheur \u00ab\u00a0Weasel\u00a0\u00bb (le petit gimmick de guitare qui suit la rythmique sur le couplet, juste impeccable), le refrain aux limites de la dissonance de \u00ab\u00a0Priest\u00a0\u00bb, le heavy \u00ab\u00a0Ixian\u00a0\u00bbet son final prot\u00e9iforme, et \u00ab\u00a0Grouper\u00a0\u00bb en cloture, empruntant au hardcore sur son premier segment pour se terminer sur quelque chose de plus riche, pos\u00e9 et lourd.<\/p>\n<p>Avec 2 ou 3 titres moins marquants, ce disque n&rsquo;est pas parfait. Il propose toutefois une musique non seulement de qualit\u00e9, mais aussi inventive, solidement ancr\u00e9e dans son territoire (Seattle, terre de grunge s&rsquo;il en est), d\u00e9veloppant un talent m\u00e9lodique tout \u00e0 fait remarquable. Une fort belle galette, de celles qu&rsquo;on aimerait trouver tous les mois dans nos haut-parleurs. Et m\u00eame sa couverture, aussi \u00e9nigmatique que son titre (m\u00ealant r\u00e9alisme dans sa technique, et imaginaire avec son code couleur d\u00e9cal\u00e9&#8230;), est r\u00e9ussie. Z\u00e9ro r\u00e9serve.<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><iframe style=\"border: 0; width: 100%; height: 120px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=1273572269\/size=large\/bgcol=ffffff\/linkcol=0687f5\/tracklist=false\/artwork=small\/track=1624529984\/transparent=true\/\" seamless=\"\"><a href=\"https:\/\/sandrider.bandcamp.com\/album\/enveletration\">Enveletration by Sandrider<\/a><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatre ! Cet \u00e9nigmatiquement d\u00e9nomm\u00e9 Enveletration est rien moins que le quatri\u00e8me disque de ce groupe \u00e9tasunien pass\u00e9 largement sous les radars, apr\u00e8s pourtant plus d&rsquo;une douzaine d&rsquo;ann\u00e9es d&rsquo;existence. Encha\u00eenant les labels obscurs, rien, hormis un coup de chance, n&rsquo;aurait pu laisser pr\u00e9juger que cette situation change un jour, tant la notori\u00e9t\u00e9 et la force [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30907,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[633,1667,1670],"tags":[11,2598,2599],"class_list":["post-30906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-633","category-disques","category-laurent","tag-11","tag-sandrider","tag-satanik-royalty-records"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sandrider - Enveletration - Desert-rock.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sandrider - Enveletration - Desert-rock.com\" \/>\n<meta property=\"og:description\" content=\"Quatre ! Cet \u00e9nigmatiquement d\u00e9nomm\u00e9 Enveletration est rien moins que le quatri\u00e8me disque de ce groupe \u00e9tasunien pass\u00e9 largement sous les radars, apr\u00e8s pourtant plus d&rsquo;une douzaine d&rsquo;ann\u00e9es d&rsquo;existence. Encha\u00eenant les labels obscurs, rien, hormis un coup de chance, n&rsquo;aurait pu laisser pr\u00e9juger que cette situation change un jour, tant la notori\u00e9t\u00e9 et la force [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html\" \/>\n<meta property=\"og:site_name\" content=\"Desert-rock.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/desertrockcom\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T05:28:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-25T17:15:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laurent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laurent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html\"},\"author\":{\"name\":\"Laurent\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/aa78023c9b441176ec5b66e541591373\"},\"headline\":\"Sandrider &#8211; Enveletration\",\"datePublished\":\"2023-04-11T05:28:18+00:00\",\"dateModified\":\"2026-02-25T17:15:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cover-Sandrider-Enveletration.jpg\",\"keywords\":[\"2023\",\"sandrider\",\"Satanik Royalty Records\"],\"articleSection\":[\"2023\",\"Disques\",\"Laurent\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html\",\"name\":\"Sandrider - Enveletration - Desert-rock.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cover-Sandrider-Enveletration.jpg\",\"datePublished\":\"2023-04-11T05:28:18+00:00\",\"dateModified\":\"2026-02-25T17:15:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#primaryimage\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cover-Sandrider-Enveletration.jpg\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cover-Sandrider-Enveletration.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/sandrider-enveletration.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sandrider &#8211; Enveletration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"name\":\"Desert-rock.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#organization\",\"name\":\"Desert-rock.com\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/logo-2.png\",\"width\":400,\"height\":182,\"caption\":\"Desert-rock.com\"},\"image\":{\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/desertrockcom\",\"https:\\\/\\\/www.instagram.com\\\/desertrockcom\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/#\\\/schema\\\/person\\\/aa78023c9b441176ec5b66e541591373\",\"name\":\"Laurent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g\",\"caption\":\"Laurent\"},\"url\":\"https:\\\/\\\/desert-rock.com\\\/site\\\/author\\\/laurent\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sandrider - Enveletration - Desert-rock.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html","og_locale":"fr_FR","og_type":"article","og_title":"Sandrider - Enveletration - Desert-rock.com","og_description":"Quatre ! Cet \u00e9nigmatiquement d\u00e9nomm\u00e9 Enveletration est rien moins que le quatri\u00e8me disque de ce groupe \u00e9tasunien pass\u00e9 largement sous les radars, apr\u00e8s pourtant plus d&rsquo;une douzaine d&rsquo;ann\u00e9es d&rsquo;existence. Encha\u00eenant les labels obscurs, rien, hormis un coup de chance, n&rsquo;aurait pu laisser pr\u00e9juger que cette situation change un jour, tant la notori\u00e9t\u00e9 et la force [&hellip;]","og_url":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html","og_site_name":"Desert-rock.com","article_publisher":"https:\/\/www.facebook.com\/desertrockcom","article_published_time":"2023-04-11T05:28:18+00:00","article_modified_time":"2026-02-25T17:15:49+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg","type":"image\/jpeg"}],"author":"Laurent","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Laurent","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#article","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html"},"author":{"name":"Laurent","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/aa78023c9b441176ec5b66e541591373"},"headline":"Sandrider &#8211; Enveletration","datePublished":"2023-04-11T05:28:18+00:00","dateModified":"2026-02-25T17:15:49+00:00","mainEntityOfPage":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"image":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg","keywords":["2023","sandrider","Satanik Royalty Records"],"articleSection":["2023","Disques","Laurent"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html","url":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html","name":"Sandrider - Enveletration - Desert-rock.com","isPartOf":{"@id":"https:\/\/desert-rock.com\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#primaryimage"},"image":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#primaryimage"},"thumbnailUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg","datePublished":"2023-04-11T05:28:18+00:00","dateModified":"2026-02-25T17:15:49+00:00","breadcrumb":{"@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/desert-rock.com\/site\/sandrider-enveletration.html"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#primaryimage","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2023\/03\/cover-Sandrider-Enveletration.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/desert-rock.com\/site\/sandrider-enveletration.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/desert-rock.com\/site\/"},{"@type":"ListItem","position":2,"name":"Sandrider &#8211; Enveletration"}]},{"@type":"WebSite","@id":"https:\/\/desert-rock.com\/site\/#website","url":"https:\/\/desert-rock.com\/site\/","name":"Desert-rock.com","description":"","publisher":{"@id":"https:\/\/desert-rock.com\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/desert-rock.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/desert-rock.com\/site\/#organization","name":"Desert-rock.com","url":"https:\/\/desert-rock.com\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/","url":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","contentUrl":"https:\/\/desert-rock.com\/site\/wp-content\/uploads\/2024\/07\/logo-2.png","width":400,"height":182,"caption":"Desert-rock.com"},"image":{"@id":"https:\/\/desert-rock.com\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/desertrockcom","https:\/\/www.instagram.com\/desertrockcom\/"]},{"@type":"Person","@id":"https:\/\/desert-rock.com\/site\/#\/schema\/person\/aa78023c9b441176ec5b66e541591373","name":"Laurent","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8aa14c0790714934c22ad8e54e4013813161233fea36f0e01005e10b26036e4?s=96&d=mm&r=g","caption":"Laurent"},"url":"https:\/\/desert-rock.com\/site\/author\/laurent"}]}},"_links":{"self":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/30906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/comments?post=30906"}],"version-history":[{"count":1,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/30906\/revisions"}],"predecessor-version":[{"id":38323,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/posts\/30906\/revisions\/38323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media\/30907"}],"wp:attachment":[{"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/media?parent=30906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/categories?post=30906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/desert-rock.com\/site\/wp-json\/wp\/v2\/tags?post=30906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}